{"id":18378,"date":"2023-08-07T14:01:35","date_gmt":"2023-08-07T12:01:35","guid":{"rendered":"https:\/\/formantia.es\/blog\/?p=18378"},"modified":"2023-08-07T18:25:09","modified_gmt":"2023-08-07T16:25:09","slug":"enfermeria-para-navarra-aspirantes-aprobados-propuesta-de-nombramiento-convocatoria-2021-31-07-2023","status":"publish","type":"post","link":"https:\/\/formantia.es\/blog\/enfermeria-para-navarra-aspirantes-aprobados-propuesta-de-nombramiento-convocatoria-2021-31-07-2023\/","title":{"rendered":"Enfermer\u00eda para Navarra: Aspirantes aprobados + propuesta de nombramiento (Convocatoria 2021)"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"18378\" class=\"elementor elementor-18378\" data-elementor-post-type=\"post\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f3d2e71 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f3d2e71\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5140b01\" data-id=\"5140b01\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f6648f8 elementor-widget elementor-widget-image\" data-id=\"f6648f8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"640\" height=\"800\" src=\"https:\/\/formantia.es\/blog\/wp-content\/uploads\/2023\/08\/358136168_750414377094085_7097475489091757377_n-819x1024.jpeg\" class=\"attachment-large size-large wp-image-18380\" alt=\"\" srcset=\"https:\/\/formantia.es\/blog\/wp-content\/uploads\/2023\/08\/358136168_750414377094085_7097475489091757377_n-819x1024.jpeg 819w, https:\/\/formantia.es\/blog\/wp-content\/uploads\/2023\/08\/358136168_750414377094085_7097475489091757377_n-240x300.jpeg 240w, https:\/\/formantia.es\/blog\/wp-content\/uploads\/2023\/08\/358136168_750414377094085_7097475489091757377_n-768x960.jpeg 768w, https:\/\/formantia.es\/blog\/wp-content\/uploads\/2023\/08\/358136168_750414377094085_7097475489091757377_n.jpeg 1080w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-1944e0d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1944e0d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-31b80bf\" data-id=\"31b80bf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8028610 elementor-widget elementor-widget-text-editor\" data-id=\"8028610\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>En cumplimiento de lo dispuesto en la base 9 de la convocatoria para la provisi\u00f3n, mediante concurso-oposici\u00f3n, de 424 puestos de Enfermero\/a, para los Organismos Aut\u00f3nomos del Departamento de Salud de la Administraci\u00f3n de la Comunidad Foral de Navarra, aprobada por Orden Foral 195E\/2021, de 10 de septiembre, de la consejera de Salud, publicada en el Bolet\u00edn Oficial de Navarra, n\u00famero 229, de 30 de septiembre de 2021, el tribunal calificador de la referida convocatoria ha presentado el <b>nombre de los aspirantes aprobados por orden de puntuaci\u00f3n obtenida y la propuesta de nombramiento<\/b> a favor de quienes cumpliendo los requisitos son aprobados con mayor puntuaci\u00f3n y tienen cabida en el n\u00famero de plazas convocadas.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-98e2b2d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"98e2b2d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-3ba47d6\" data-id=\"3ba47d6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4409530 elementor-widget elementor-widget-text-editor\" data-id=\"4409530\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\"><a href=\"https:\/\/bon.navarra.es\/es\/anuncio\/-\/texto\/2023\/157\/1\" target=\"_blank\" rel=\"noopener\"><span style=\"text-decoration: underline;\">\ud83d\udc49 Accede al bolet\u00edn con el listado aqu\u00ed<\/span><\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b21d640 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b21d640\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c9058bf\" data-id=\"c9058bf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6fb7c6c elementor-widget elementor-widget-heading\" data-id=\"6fb7c6c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Plazo para presentar<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-b6b62bd elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b6b62bd\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b605f5f\" data-id=\"b605f5f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-14bc5c8 elementor-widget elementor-widget-text-editor\" data-id=\"14bc5c8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Las personas aspirantes propuestas deber\u00e1n presentar, a trav\u00e9s del Registro General Electr\u00f3nico de la Administraci\u00f3n de la Comunidad Foral de Navarra, <b>dentro de los 30 d\u00edas naturales<\/b> siguientes al de publicaci\u00f3n de la presente propuesta en el Bolet\u00edn Oficial de Navarra, la documentaci\u00f3n exigida en la citada base.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7ca80df elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7ca80df\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-847c667\" data-id=\"847c667\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4db4075 elementor-widget elementor-widget-shortcode\" data-id=\"4db4075\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"9739\" class=\"elementor elementor-9739\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a53e4e7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a53e4e7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-500f480\" data-id=\"500f480\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cd0f367 elementor-widget elementor-widget-heading\" data-id=\"cd0f367\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Detr\u00e1s de un buen puesto hay un buen m\u00e9todo<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-aa13946 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"aa13946\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-bd1e23b\" data-id=\"bd1e23b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33cbb24 elementor-widget elementor-widget-text-editor\" data-id=\"33cbb24\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Somos especialistas en ayudarte a conseguir tus metas\u00a0<strong>sin renunciar a tu vida.\u00a0<\/strong><\/p><p>Por eso, con nuestro\u00a0<strong>M\u00e9todo Formantia<\/strong>, podr\u00e1s conseguir el trabajo de tu vida sin dejarte la vida en ello.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8fccfa0 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8fccfa0\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-00c4717\" data-id=\"00c4717\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-deeef6a elementor-widget elementor-widget-text-editor\" data-id=\"deeef6a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\">\u00bfTe gustar\u00eda saber c\u00f3mo?, agenda una llamada: \u260e\ufe0f<strong>\u00a0<\/strong><span style=\"text-decoration: underline;\"><strong><a href=\"https:\/\/reuniones.clientify.com\/#\/formantia_admisiones\/asesora\" target=\"_blank\" rel=\"noopener\">Agendar Llamada<\/a><\/strong><\/span><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7fcc554 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7fcc554\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-609da58\" data-id=\"609da58\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-596dfc8 elementor-widget elementor-widget-shortcode\" data-id=\"596dfc8\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"section\" data-elementor-id=\"9552\" class=\"elementor elementor-9552\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-05489eb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"05489eb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-84207f9\" data-id=\"84207f9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26e0fb4 elementor-widget elementor-widget-text-editor\" data-id=\"26e0fb4\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: left;\"><strong>Y si quieres estar informado de todo lo concerniente a este proceso y de las pr\u00f3ximas convocatorias suscr\u00edbete ahora a nuestra Newsletter.<\/strong><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d88c18f elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d88c18f\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-88a9a6e\" data-id=\"88a9a6e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9d1c5f9 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"9d1c5f9\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/formantia.es\/blog\/newsletter-formantia\/?utm_source=web&#038;utm_medium=blog&#038;utm_campaign=post&#038;utm_content=quiero+estar+informado\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">\ud83d\udc49 Quiero estar informado<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-a69fd73 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"a69fd73\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-698fa72\" data-id=\"698fa72\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bcdc22e elementor-widget elementor-widget-shortcode\" data-id=\"bcdc22e\" data-element_type=\"widget\" data-widget_type=\"shortcode.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-shortcode\">\t\t<div data-elementor-type=\"page\" data-elementor-id=\"9734\" class=\"elementor elementor-9734\" data-elementor-post-type=\"elementor_library\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e4423bc elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e4423bc\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-7f66c1a\" data-id=\"7f66c1a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8b2df82 elementor-widget elementor-widget-text-editor\" data-id=\"8b2df82\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p style=\"text-align: center;\">Comp\u00e1rtelo en tus redes sociales<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-718fc0a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"718fc0a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-5123c5b\" data-id=\"5123c5b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-61ebd13 elementor-share-buttons--skin-minimal elementor-share-buttons--shape-circle elementor-share-buttons--align-center elementor-share-buttons--view-icon elementor-grid-0 elementor-share-buttons--color-official elementor-widget elementor-widget-share-buttons\" data-id=\"61ebd13\" data-element_type=\"widget\" data-widget_type=\"share-buttons.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-grid\" role=\"list\">\n\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_facebook\" role=\"button\" tabindex=\"0\" aria-label=\"Compartir en facebook\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-facebook\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_whatsapp\" role=\"button\" tabindex=\"0\" aria-label=\"Compartir en whatsapp\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-whatsapp\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_twitter\" role=\"button\" tabindex=\"0\" aria-label=\"Compartir en twitter\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-twitter\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_linkedin\" role=\"button\" tabindex=\"0\" aria-label=\"Compartir en linkedin\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-linkedin\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-grid-item\" role=\"listitem\">\n\t\t\t\t\t\t<div class=\"elementor-share-btn elementor-share-btn_telegram\" role=\"button\" tabindex=\"0\" aria-label=\"Compartir en telegram\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"elementor-share-btn__icon\">\n\t\t\t\t\t\t\t\t<i class=\"fab fa-telegram\" aria-hidden=\"true\"><\/i>\t\t\t\t\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-8a563b1 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"8a563b1\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8dd34de\" data-id=\"8dd34de\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4d3f701 elementor-widget elementor-widget-text-editor\" data-id=\"4d3f701\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Disclaimer\/aviso:<\/p><p>La informaci\u00f3n provista en los post del blog de Formantia no constituye ni pretende constituir asesoramiento legal personalizado; toda la informaci\u00f3n facilitada es solo para fines informativos generales y pueden no constituir informaci\u00f3n exhaustiva. <br \/>En la medida que el blog contenga enlaces a otros contenidos de terceros, dichos enlaces son solo para la ampliar la informaci\u00f3n del lector, usuario o navegador; Formantia no recomienda ni respalda dicho contenido. <br \/>Se renuncia expresamente a toda responsabilidad con respecto a las acciones tomadas o no tomadas en base al contenido de los post del blog.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t\n<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>En cumplimiento de lo dispuesto en la base 9 de la convocatoria para la provisi\u00f3n, mediante concurso-oposici\u00f3n, de 424 puestos de Enfermero\/a, para los Organismos Aut\u00f3nomos del Departamento de Salud de la Administraci\u00f3n de la Comunidad Foral de Navarra, aprobada por Orden Foral 195E\/2021, de 10 de septiembre, de la consejera de Salud, publicada en [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","footnotes":""},"categories":[186],"tags":[23],"class_list":["post-18378","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-enfermeria","entry"],"_links":{"self":[{"href":"https:\/\/formantia.es\/blog\/wp-json\/wp\/v2\/posts\/18378","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/formantia.es\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/formantia.es\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/formantia.es\/blog\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/formantia.es\/blog\/wp-json\/wp\/v2\/comments?post=18378"}],"version-history":[{"count":16,"href":"https:\/\/formantia.es\/blog\/wp-json\/wp\/v2\/posts\/18378\/revisions"}],"predecessor-version":[{"id":18414,"href":"https:\/\/formantia.es\/blog\/wp-json\/wp\/v2\/posts\/18378\/revisions\/18414"}],"wp:attachment":[{"href":"https:\/\/formantia.es\/blog\/wp-json\/wp\/v2\/media?parent=18378"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/formantia.es\/blog\/wp-json\/wp\/v2\/categories?post=18378"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/formantia.es\/blog\/wp-json\/wp\/v2\/tags?post=18378"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}